{"id":204,"date":"2015-11-06T13:34:11","date_gmt":"2015-11-06T13:34:11","guid":{"rendered":"http:\/\/blog.tu-dresden.de\/litfasssaeule\/?p=204"},"modified":"2015-11-06T13:35:11","modified_gmt":"2015-11-06T13:35:11","slug":"verbundprojekt-lehrpraxis-im-transfer-geht-in-die-zweite-runde","status":"publish","type":"post","link":"https:\/\/blog.tu-dresden.de\/litfasssaeule\/2015\/11\/06\/verbundprojekt-lehrpraxis-im-transfer-geht-in-die-zweite-runde\/","title":{"rendered":"Verbundprojekt Lehrpraxis im Transfer geht in die zweite Runde"},"content":{"rendered":"<p>Auf der heutigen Pressekonferenz des Bundesministerium f\u00fcr Bildung und Forschung (BMBF) und der Gemeinsamen Wissenschaftskonferenz (GWK) wurde bekannt gegeben, dass das Verbundprojekt Lehrpraxis im Transfer f\u00fcr die zweite F\u00f6rderperiode des Qualit\u00e4tspakt Lehre ausgew\u00e4hlt wurde. Das Verbundprojekt Lehrpraxis im Transfer plus wird von Januar 2017 bis Dezember 2020 mit einer F\u00f6rdersumme von 5,2 Millionen aus Mitteln des Bundesministerium f\u00fcr Bildung und Forschung im Rahmen des Qualit\u00e4tspakt Lehre gef\u00f6rdert und vom Hochschuldidaktischen Zentrum Sachsen (HDS) koordiniert.<\/p>\n<p>Beteiligte Verbundpartner sind die vier s\u00e4chsischen Universit\u00e4ten (Universit\u00e4t Leipzig, TU Dresden, TU Chemnitz, TU Bergakademie Freiberg) sowie f\u00fcnf Hochschulen f\u00fcr Angewandte Wissenschaften (Hochschule f\u00fcr Technik, Wirtschaft und Kultur Leipzig, Hochschule f\u00fcr Technik und Wirtschaft Dresden, Hochschule Zittau\/G\u00f6rlitz, Hochschule Mittweida, Wests\u00e4chsische Hochschule Zwickau)<\/p>\n<p>Weitere Informationen \u00fcber das Verbundprojekt unter: www.lehrpraxis-im-transfer.de.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auf der heutigen Pressekonferenz des Bundesministerium f\u00fcr Bildung und Forschung (BMBF) und der Gemeinsamen Wissenschaftskonferenz (GWK) wurde bekannt gegeben, dass das Verbundprojekt Lehrpraxis im Transfer f\u00fcr die zweite F\u00f6rderperiode des Qualit\u00e4tspakt Lehre ausgew\u00e4hlt wurde. Das Verbundprojekt Lehrpraxis im Transfer plus wird von Januar 2017 bis Dezember 2020 mit einer F\u00f6rdersumme von 5,2 Millionen aus Mitteln [&hellip;]<\/p>\n","protected":false},"author":165,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,354],"tags":[415,4443,537],"class_list":["post-204","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-hd","tag-hds","tag-professionalisierung","tag-projektforderung"],"_links":{"self":[{"href":"https:\/\/blog.tu-dresden.de\/litfasssaeule\/wp-json\/wp\/v2\/posts\/204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.tu-dresden.de\/litfasssaeule\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.tu-dresden.de\/litfasssaeule\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.tu-dresden.de\/litfasssaeule\/wp-json\/wp\/v2\/users\/165"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.tu-dresden.de\/litfasssaeule\/wp-json\/wp\/v2\/comments?post=204"}],"version-history":[{"count":2,"href":"https:\/\/blog.tu-dresden.de\/litfasssaeule\/wp-json\/wp\/v2\/posts\/204\/revisions"}],"predecessor-version":[{"id":207,"href":"https:\/\/blog.tu-dresden.de\/litfasssaeule\/wp-json\/wp\/v2\/posts\/204\/revisions\/207"}],"wp:attachment":[{"href":"https:\/\/blog.tu-dresden.de\/litfasssaeule\/wp-json\/wp\/v2\/media?parent=204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.tu-dresden.de\/litfasssaeule\/wp-json\/wp\/v2\/categories?post=204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.tu-dresden.de\/litfasssaeule\/wp-json\/wp\/v2\/tags?post=204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}